{"id":4390,"date":"2024-01-30T15:01:55","date_gmt":"2024-01-30T14:01:55","guid":{"rendered":"https:\/\/leprogres.gnsis.ch\/rechtlich\/"},"modified":"2024-11-07T23:22:53","modified_gmt":"2024-11-07T22:22:53","slug":"rechtlich","status":"publish","type":"page","link":"https:\/\/reaa.ch\/de\/startseite\/rechtlich\/","title":{"rendered":"Rechtlich"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4390\" class=\"elementor elementor-4390 elementor-786\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31043d0 e-flex e-con-boxed e-con e-parent\" data-id=\"31043d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f628c09 elementor-widget elementor-widget-spacer\" data-id=\"f628c09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43fa5039 e-con-full e-flex e-con e-parent\" data-id=\"43fa5039\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ff6fc1 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0ff6fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fassung vom 05. November 2024<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6467f1eb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6467f1eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: left;\">Verlag<\/h4>\n<p style=\"text-align: left;\">Oberster Rat der REAA der Schweizerischen Kanzlei<br \/>rue du Petit-Beaulieu 1<br \/>CH-1004 Lausanne<\/p>\n<h4 style=\"text-align: left;\">Unterkunft<\/h4>\n<p style=\"text-align: left;\">Diese Website wird von Infomaniak Network SA, Rue Eug\u00e8ne Marziano 25, 1227 Les Acacias (GE), Schweiz, gehostet.<\/p>\n<h4 style=\"text-align: left;\">Erkl\u00e4rung<\/h4>\n<p style=\"text-align: left;\">Der Schutz personenbezogener Daten auf der Website:<\/p>\n<p style=\"text-align: left;\">\u00b7 Ohne Ihr Wissen werden keine personenbezogenen Daten gesammelt.<br \/>\u00b7 Es werden keine personenbezogenen Daten an Dritte weitergegeben.<br \/>\u00b7 Die Informationen werden nur zum Zwecke der Verwaltung Ihrer Anfrage und der internen Statistiken bei der REAA erhoben.<\/p>\n<h4 style=\"text-align: left;\">Personenbezogene Daten<\/h4>\n<p style=\"text-align: left;\">Sie haben das Recht, auf Ihre personenbezogenen Daten zuzugreifen und diese zu berichtigen. Wenn Sie von diesem Recht Gebrauch machen m\u00f6chten, wenden Sie sich bitte an den Webmaster unter folgender Adresse: <a href=\"mailto:chancellerie@reaa.ch\" target=\"_blank\" rel=\"noopener\">chancellerie@reaa.ch<\/a><\/p>\n<p style=\"text-align: left;\">Die betroffenen Personen wurden \u00fcber ihre Rechte informiert. Das Zugriffsrecht ist sofort auf der Website. Das Recht auf Berichtigung kann ausge\u00fcbt werden, indem Sie sich an den Webmaster unter folgender Adresse wenden: <a href=\"mailto:chancellerie@reaa.ch\" target=\"_blank\" rel=\"noopener\">chancellerie@reaa.ch<\/a><\/p>\n<h4 style=\"text-align: left;\">Droit d&#8217;auteur &#8211; Urheberrecht<\/h4>\n<p style=\"text-align: left;\">Alle Vervielf\u00e4ltigungsrechte sind vorbehalten, auch f\u00fcr herunterladbare Dokumente und ikonografische und fotografische Darstellungen.<\/p>\n<p style=\"text-align: left;\">Die Vervielf\u00e4ltigung der gesamten oder eines Teils dieser Website auf einem elektronischen Medium ist ohne die ausdr\u00fcckliche Genehmigung des Herausgebers strengstens untersagt.<\/p>\n<p style=\"text-align: left;\">Die Vervielf\u00e4ltigung der Texte dieser Website auf Papier, insbesondere im Bildungskontext, ist unter Einhaltung der folgenden drei Bedingungen gestattet: <br \/>&#8211; kostenlose Verteilung, <br \/>&#8211; Achtung der Integrit\u00e4t der reproduzierten Dokumente: keine Modifikation oder \u00c4nderung jeglicher Art, <br \/>&#8211; klare und lesbare Quellenangabe in folgender Form: <br \/>&#8220;Dieses Dokument stammt von der REAA-Website: http:\/\/www.reaa.ch. Die Vervielf\u00e4ltigungsrechte sind vorbehalten und streng begrenzt.&#8221;<\/p>\n<p style=\"text-align: left;\">Die Internetadresse der REAA-Website muss in der Referenz angegeben werden. F\u00fcr andere Nutzungen wenden Sie sich bitte an den Standortleiter.<\/p>\n<p style=\"text-align: left;\">Die auf dieser Website erw\u00e4hnten Marken sind von den Unternehmen eingetragen, denen sie geh\u00f6ren.<\/p>\n<h4 style=\"text-align: left;\">Operation<\/h4>\n<p style=\"text-align: left;\">Wenn Sie Anmerkungen zum Betrieb der Website haben, senden Sie bitte eine Nachricht an den <a href=\"mailto:chancellerie@reaa.ch\" target=\"_blank\" rel=\"noopener\">Webmaster chancellerie@reaa.ch<\/a> oder schreiben Sie an<\/p>\n<p style=\"text-align: left;\">Oberster Rat der RRLG der Schweiz<br \/>Kanzleramt<br \/>rue du Petit-Beaulieu 1<br \/>CH-1004 Lausanne<\/p>\n<h4 style=\"text-align: left;\">Cookies<\/h4>\n<p style=\"text-align: left;\">Die reaa.ch Website platziert ein Cookie auf Ihrem Computer.<\/p>\n<p style=\"text-align: left;\">Es speichert Informationen \u00fcber Ihr Surfen auf unserer Website (die von Ihnen besuchten Seiten, Datum und Uhrzeit der Konsultation usw.). Wir werden diese Informationen bei Ihren n\u00e4chsten Besuchen lesen k\u00f6nnen.<\/p>\n<p style=\"text-align: left;\">Dieses Cookie erm\u00f6glicht es uns nicht, Sie zu identifizieren.<\/p>\n<p style=\"text-align: left;\">Sie k\u00f6nnen der Speicherung von Cookies widersprechen, indem Sie Ihren Browser wie folgt einstellen:<\/p>\n<p style=\"text-align: left;\">* F\u00fcr Mozilla Firefox:<br \/>W\u00e4hlen Sie das Men\u00fc &#8220;Werkzeug&#8221; und dann &#8220;Optionen&#8221;<br \/>Klicken Sie auf das &#8220;Datenschutz&#8221;-Symbol<br \/>Suchen Sie das Men\u00fc &#8220;Cookie&#8221; und w\u00e4hlen Sie die Optionen aus, die Ihnen passen<\/p>\n<p style=\"text-align: left;\">* F\u00fcr Microsoft Internet Explorer:<br \/>W\u00e4hlen Sie das Men\u00fc &#8220;Extras&#8221; und dann &#8220;Internetoptionen&#8221;. <br \/>Klicken Sie auf die Registerkarte &#8220;Datenschutz&#8221; <br \/>W\u00e4hlen Sie die gew\u00fcnschte Stufe mit dem Schieberegler aus.<\/p>\n<p style=\"text-align: left;\">* F\u00fcr Google Chrome:<br \/>W\u00e4hlen Sie das Men\u00fc &#8220;Optionen&#8221; &#8211; &#8220;Erweiterte Optionen&#8221;<br \/>Klicken Sie auf &#8220;Datenschutz&#8221; &#8211; &#8220;Inhaltseinstellungen&#8221;<br \/>Suchen Sie das Men\u00fc &#8220;Cookies&#8221; und w\u00e4hlen Sie die Optionen aus, die Ihnen passen<\/p>\n<p style=\"text-align: left;\">* F\u00fcr Oper:<br \/>W\u00e4hlen Sie das Men\u00fc&gt; &#8220;Datei&#8221;&#8221;Einstellungen&#8221;<br \/>Privatsph\u00e4re<\/p>\n<h4 style=\"text-align: left;\">F\u00fcr<\/h4>\n<p>Gerichtsstand im Streitfall ist Lausanne, und der franz\u00f6sische Text ist verbindlich.<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52748ea e-flex e-con-boxed e-con e-parent\" data-id=\"52748ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4995b24 elementor-widget elementor-widget-spacer\" data-id=\"4995b24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fassung vom 05. November 2024 Verlag Oberster Rat der REAA der Schweizerischen Kanzleirue du Petit-Beaulieu 1CH-1004 Lausanne Unterkunft Diese Website wird von Infomaniak Network SA, Rue Eug\u00e8ne Marziano 25, 1227 Les Acacias (GE), Schweiz, gehostet. Erkl\u00e4rung Der Schutz personenbezogener Daten auf der Website: \u00b7 Ohne Ihr Wissen werden keine personenbezogenen Daten gesammelt.\u00b7 Es werden keine [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":4287,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4390","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/reaa.ch\/de\/wp-json\/wp\/v2\/pages\/4390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reaa.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/reaa.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/reaa.ch\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reaa.ch\/de\/wp-json\/wp\/v2\/comments?post=4390"}],"version-history":[{"count":3,"href":"https:\/\/reaa.ch\/de\/wp-json\/wp\/v2\/pages\/4390\/revisions"}],"predecessor-version":[{"id":10180,"href":"https:\/\/reaa.ch\/de\/wp-json\/wp\/v2\/pages\/4390\/revisions\/10180"}],"up":[{"embeddable":true,"href":"https:\/\/reaa.ch\/de\/wp-json\/wp\/v2\/pages\/4287"}],"wp:attachment":[{"href":"https:\/\/reaa.ch\/de\/wp-json\/wp\/v2\/media?parent=4390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}