{"id":16884,"date":"2025-11-08T22:30:42","date_gmt":"2025-11-08T21:30:42","guid":{"rendered":"https:\/\/reaa.ch\/casa\/intranet\/supporto\/"},"modified":"2025-11-09T15:57:40","modified_gmt":"2025-11-09T14:57:40","slug":"supporto","status":"publish","type":"page","link":"https:\/\/reaa.ch\/it\/casa\/intranet\/supporto\/","title":{"rendered":"Supporto"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16884\" class=\"elementor elementor-16884 elementor-16871\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58d815b e-con-full e-flex e-con e-parent\" data-id=\"58d815b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-381ccbd2 e-con-full e-flex e-con e-child\" data-id=\"381ccbd2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-119c33a0 e-con-full e-flex e-con e-child\" data-id=\"119c33a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6135adb0 elementor-widget elementor-widget-heading\" data-id=\"6135adb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Supporto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c514b65 elementor-widget elementor-widget-spacer\" data-id=\"5c514b65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7743593 e-grid e-con-full e-con e-child\" data-id=\"7743593\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc0f088 elementor-widget elementor-widget-text-editor\" data-id=\"fc0f088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\">La mia prima connessione<\/h4><p>Il Consiglio Supremo delle RSAA svizzere \u00e8 lieto di darti il benvenuto su Intranet.<\/p><p>Per accedere per la prima volta, utilizza la procedura<a href=\"https:\/\/reaa.ch\/wp-login.php?action=lostpassword\" target=\"_blank\" rel=\"noopener\">&#8220;Hai dimenticato la password<\/a>?&#8221; (&#8220;mot de passe oubli\u00e9&#8221;), utilizzando l&#8217;indirizzo e-mail che hai fornito alla segreteria del workshop.<\/p><ul><li>Se non ricordi il tuo indirizzo e-mail, non hai altra scelta che chiederlo alla tua segreteria.<\/li><\/ul><p> <\/p><p>Se hai qualche problema, non esitare a chiedere aiuto tramite il <a href=\"https:\/\/reaa.ch\/it\/casa\/modulo-di-contatto\/\" target=\"_blank\" rel=\"noopener\">Modulo di contatto<\/a>. Uno dei nostri webmaster ti risponder\u00e0. <\/p><p>Ottima connessione!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9551ee3 elementor-widget elementor-widget-text-editor\" data-id=\"9551ee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\">Hai dimenticato la password (&#8220;mot de passe oubli\u00e9&#8221;)?<\/h4><p>Se non ricordi la tua password, ecco cosa fare.<\/p><ol><li>Prepara il tuo indirizzo e-mail: quello che hai fornito alla segreteria del workshop.<br><strong>Se non ricordi il tuo indirizzo e-mail<\/strong>, chiedilo alla tua segreteria o agli amministratori del sito tramite il <a href=\"https:\/\/reaa.ch\/it\/casa\/modulo-di-contatto\/\" target=\"_blank\" rel=\"noopener\">modulo di contatto<\/a>.<\/li><li>Clicca su &#8220;dimentica la password&#8221;.<\/li><li>Il sistema ti chieder\u00e0 il tuo indirizzo e-mail.<\/li><li>Clicca sul pulsante [Genera password]<br>Il sistema ti chieder\u00e0 di controllare la tua casella di posta elettronica.<br><strong>Se non ricevi nulla nella tua casella di posta elettronica<\/strong>, \u00e8 possibile che l&#8217;indirizzo non sia quello registrato sul sito. Dovrai chiedere alla segreteria del tuo laboratorio o agli amministratori del sito tramite il <a href=\"https:\/\/reaa.ch\/it\/casa\/modulo-di-contatto\/\" target=\"_blank\" rel=\"noopener\">modulo di contatto<\/a>. <\/li><li>Nella tua e-mail c&#8217;\u00e8 un link che ti permette di generare una password.<br>Questa password viene visualizzata in una nuova finestra del browser. \u00c8 molto complessa e difficile da ricordare.<br>Quindi la soluzione \u00e8 cancellarla e inserire la tua, rispettando quanto segue:<br>&#8211; 12 caratteri minimo<br>&#8211; 1 lettera maiuscola minimo<br>&#8211; 1 carattere speciale minimo<br>&#8211; nessuna ripetizione di caratteri (&#8217;99&#8217; possibile; &#8216;999&#8217; non \u00e8 accettato) <\/li><li>Inserisci la tua password. Assicurati che il pulsante [Salva password] sia attivo. Questo indica che hai seguito le istruzioni per la password.<br>Nota: non esitare a cliccare sull&#8217;occhio per visualizzare la tua password.  <\/li><li>Il sistema risponde: &#8220;La tua password \u00e8 stata resettata&#8221; e hai ricevuto una notifica (e-mail) che conferma la completamento dell&#8217;operazione.<\/li><li>Ora torna su &gt; Intranet per effettuare il login.<\/li><\/ol><p> <\/p><p>Se non funziona, riprova seguendo attentamente i passaggi e le istruzioni.<\/p><p>Il sistema blocca il tuo account dopo un certo numero di tentativi di connessione. Non forniamo questo numero. Quindi non esitare a contattare gli amministratori del sito tramite il <a href=\"https:\/\/reaa.ch\/it\/casa\/modulo-di-contatto\/\" target=\"_blank\" rel=\"noopener\">Modulo di contatto<\/a>. Siamo qui per aiutarti.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d374675 e-flex e-con-boxed e-con e-child\" data-id=\"7d374675\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19b7ef5 elementor-widget elementor-widget-spacer\" data-id=\"19b7ef5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La mia prima connessione Il Consiglio Supremo delle RSAA svizzere \u00e8 lieto di darti il benvenuto su Intranet. Per accedere per la prima volta, utilizza la procedura&#8220;Hai dimenticato la password?&#8221; (&#8220;mot de passe oubli\u00e9&#8221;), utilizzando l&#8217;indirizzo e-mail che hai fornito alla segreteria del workshop. Se non ricordi il tuo indirizzo e-mail, non hai altra scelta [&hellip;]<\/p>\n","protected":false},"author":2337,"featured_media":0,"parent":4275,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16884","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/reaa.ch\/it\/wp-json\/wp\/v2\/pages\/16884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reaa.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/reaa.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/reaa.ch\/it\/wp-json\/wp\/v2\/users\/2337"}],"replies":[{"embeddable":true,"href":"https:\/\/reaa.ch\/it\/wp-json\/wp\/v2\/comments?post=16884"}],"version-history":[{"count":3,"href":"https:\/\/reaa.ch\/it\/wp-json\/wp\/v2\/pages\/16884\/revisions"}],"predecessor-version":[{"id":16917,"href":"https:\/\/reaa.ch\/it\/wp-json\/wp\/v2\/pages\/16884\/revisions\/16917"}],"up":[{"embeddable":true,"href":"https:\/\/reaa.ch\/it\/wp-json\/wp\/v2\/pages\/4275"}],"wp:attachment":[{"href":"https:\/\/reaa.ch\/it\/wp-json\/wp\/v2\/media?parent=16884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}